{"id":15985,"date":"2025-12-24T02:22:43","date_gmt":"2025-12-24T02:22:43","guid":{"rendered":"https:\/\/www.dgcrane.com\/?post_type=posts&#038;p=15985"},"modified":"2025-12-24T02:22:46","modified_gmt":"2025-12-24T02:22:46","slug":"5t-european-single-girder-overhead-crane-delivered-to-indonesia","status":"publish","type":"posts","link":"https:\/\/www.dgcrane.com\/de\/posts\/5t-european-single-girder-overhead-crane-delivered-to-indonesia\/","title":{"rendered":"5-Tonnen-Eintr\u00e4ger-Br\u00fcckenkran aus europ\u00e4ischer Bauart nach Indonesien geliefert"},"content":{"rendered":"<p>Im Februar 2025 begann DGCRANE die Zusammenarbeit mit einem indonesischen Kunden, der als Zulieferer f\u00fcr seinen Endkunden fungierte. Die erste Projektbesprechung fand am 18. Februar 2025 statt, gefolgt vom ersten Angebot am 21. Februar 2025.<\/p>\n\n\n\n<p>Um die optimale Hebel\u00f6sung f\u00fcr den Endkunden zu gew\u00e4hrleisten, besuchte dieser am 6. M\u00e4rz 2025 das Werk von DGCRANE. W\u00e4hrend des Werksbesuchs f\u00fchrte das technische Team von DGCRANE ausf\u00fchrliche Gespr\u00e4che mit dem Kunden und unterst\u00fctzte ihn bei der Auswahl der optimalen L\u00f6sung zwischen einem Portalkran und einem Br\u00fcckenkransystem. Basierend auf den tats\u00e4chlichen Arbeitsbedingungen und Anwendungsanforderungen wurde schlie\u00dflich die HD-Eintr\u00e4ger-Br\u00fcckenkranl\u00f6sung nach europ\u00e4ischer Bauart ausgew\u00e4hlt.<\/p>\n\n\n\n<p>Nach detaillierter technischer Best\u00e4tigung und kommerziellen Verhandlungen erfolgte die Zahlung durch den Kunden am 25. Juli 2025. Der Kran wurde erfolgreich gefertigt und gem\u00e4\u00df CIF-Bedingungen verschifft. DGCRANE \u00fcbernahm die gesamte Logistik bis zum Hafen von Belawan in Indonesien. Die Verschiffung wurde am 28. September 2025 reibungslos abgeschlossen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1332\" src=\"https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/European-Single-Girder-Overhead-Crane-end-beam.jpg\" alt=\"\" class=\"wp-image-15988\" srcset=\"https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/European-Single-Girder-Overhead-Crane-end-beam.jpg 2000w, https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/European-Single-Girder-Overhead-Crane-end-beam-1536x1023.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"2000\" src=\"https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/European-Single-Girder-Overhead-Crane-main-beam-2.jpg\" alt=\"\" class=\"wp-image-15989\" srcset=\"https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/European-Single-Girder-Overhead-Crane-main-beam-2.jpg 1500w, https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/European-Single-Girder-Overhead-Crane-main-beam-2-1152x1536.jpg 1152w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1279\" height=\"1706\" src=\"https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/delivery.jpg\" alt=\"\" class=\"wp-image-15990\" srcset=\"https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/delivery.jpg 1279w, https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/delivery-1152x1536.jpg 1152w\" sizes=\"(max-width: 1279px) 100vw, 1279px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1279\" height=\"1706\" src=\"https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/delivery-2.jpg\" alt=\"\" class=\"wp-image-15991\" srcset=\"https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/delivery-2.jpg 1279w, https:\/\/www.dgcrane.com\/wp-content\/uploads\/2025\/12\/delivery-2-1152x1536.jpg 1152w\" sizes=\"(max-width: 1279px) 100vw, 1279px\" \/><\/figure>\n\n\n\n<p>Dieses Projekt wurde von der technischen Beratung und Werksinspektion \u00fcber die Fertigung und Logistik bis hin zur Auslieferung reibungslos abgewickelt. Die erfolgreiche Lieferung unterstreicht einmal mehr die Kompetenz von DGCRANE im Bereich europ\u00e4ischer Kranl\u00f6sungen, professioneller Projektkoordination und internationaler CIF-Lieferungen.<\/p>\n\n\n\n<p>DGCRANE ist weiterhin bestrebt, seinen globalen Partnern zuverl\u00e4ssige, effiziente und ma\u00dfgeschneiderte Hebel\u00f6sungen anzubieten und so deren Erfolg auf den lokalen M\u00e4rkten zu unterst\u00fctzen.<\/p>","protected":false},"excerpt":{"rendered":"Im Februar 2025 begann DGCRANE die Zusammenarbeit mit einem indonesischen Kunden, der als Zulieferer f\u00fcr seinen Endkunden fungierte. Die erste Projektbesprechung fand am 18. Februar 2025 statt, gefolgt vom ersten Angebot am 21. Februar 2025. Um die optimale Hebel\u00f6sung f\u00fcr den Endkunden zu gew\u00e4hrleisten, besuchte der Kunde im M\u00e4rz [\u2026] das Werk von DGCRANE.","protected":false},"featured_media":15986,"parent":0,"menu_order":0,"template":"single-case.php","posts_category":[4],"posts_tag":[380,6,74],"class_list":["post-15985","posts","type-posts","status-publish","has-post-thumbnail","hentry","posts_category-cases","posts_tag-indonesia","posts_tag-overhead-crane","posts_tag-single-girder-overhead-crane"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dgcrane.com\/de\/wp-json\/wp\/v2\/xmxposts\/15985"}],"collection":[{"href":"https:\/\/www.dgcrane.com\/de\/wp-json\/wp\/v2\/xmxposts"}],"about":[{"href":"https:\/\/www.dgcrane.com\/de\/wp-json\/wp\/v2\/types\/posts"}],"version-history":[{"count":2,"href":"https:\/\/www.dgcrane.com\/de\/wp-json\/wp\/v2\/xmxposts\/15985\/revisions"}],"predecessor-version":[{"id":15992,"href":"https:\/\/www.dgcrane.com\/de\/wp-json\/wp\/v2\/xmxposts\/15985\/revisions\/15992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dgcrane.com\/de\/wp-json\/wp\/v2\/media\/15986"}],"wp:attachment":[{"href":"https:\/\/www.dgcrane.com\/de\/wp-json\/wp\/v2\/media?parent=15985"}],"wp:term":[{"taxonomy":"posts_category","embeddable":true,"href":"https:\/\/www.dgcrane.com\/de\/wp-json\/wp\/v2\/posts_category?post=15985"},{"taxonomy":"posts_tag","embeddable":true,"href":"https:\/\/www.dgcrane.com\/de\/wp-json\/wp\/v2\/posts_tag?post=15985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}